{"id":45166,"date":"2024-05-16T15:09:01","date_gmt":"2024-05-16T13:09:01","guid":{"rendered":"https:\/\/tom-mallorca.com\/terapias\/diathermie\/"},"modified":"2025-09-09T15:17:24","modified_gmt":"2025-09-09T13:17:24","slug":"diatermia","status":"publish","type":"page","link":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/","title":{"rendered":"Diatermia"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHero\u00bb _builder_version=\u00bb4.18.1&#8243; custom_padding=\u00bb0|0px|0px|0px|false|false\u00bb bottom_divider_height=\u00bb0px\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#efefef\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.0&#8243; width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb||0px|\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb custom_padding=\u00bb0|0px|27px|0px|false|false\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.18.1&#8243; custom_padding=\u00bb6%||6%|10%|false|false\u00bb custom_padding_tablet=\u00bb50px|50px|50px|50px\u00bb custom_padding_phone=\u00bb50px|50px|50px|50px\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb padding_tablet=\u00bb50px|50px|50px|50px\u00bb padding_last_edited=\u00bbon|tablet\u00bb custom_padding__hover=\u00bb|||\u00bb padding_phone=\u00bb50px|50px|50px|50px\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font=\u00bbMontserrat|300|||||||\u00bb text_text_color=\u00bb#677a92&#8243; text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bb|600|||||||\u00bb header_font_size=\u00bb34px\u00bb header_line_height=\u00bb1.3em\u00bb header_2_font=\u00bb||||||||\u00bb max_width=\u00bb600px\u00bb custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb0px|50px||50px\u00bb custom_margin_phone=\u00bb|20px||\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb|||\u00bb text_line_height_tablet=\u00bb1.8em\u00bb text_line_height_phone=\u00bb1.8em\u00bb text_line_height_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb\u00bb header_font_size_phone=\u00bb36px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bboff|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1 class=\"page-title\">Diatermia<\/h1>\n<h3>Tecarterapia (transferencia de energ\u00eda capacitiva y resistiva)<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb quote_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbMontserrat|300|||||||\u00bb header_2_text_color=\u00bb#212d3b\u00bb header_2_font_size=\u00bb40px\u00bb header_2_line_height=\u00bb1.5em\u00bb max_width=\u00bb600px\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb0px|50px||50px\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Se trata de una forma de terapia que utiliza corrientes el\u00e9ctricas y, por tanto, pertenece al grupo de las electroterapias. Aqu\u00ed se aplica corriente de una frecuencia determinada, que estimula el tejido biol\u00f3gico. Esto tiene un efecto antiinflamatorio y estimula y acelera los procesos naturales de curaci\u00f3n. Dependiendo de los ajustes del aparato, el tejido tambi\u00e9n puede calentarse. A diferencia de todas las dem\u00e1s formas de tratamiento t\u00e9rmico, el calor se genera en el propio tejido (calor end\u00f3geno).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; custom_padding=\u00bb8%||||false|false\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2024\/06\/Diathermie-755&#215;1024.jpg\u00bb title_text=\u00bbDiatermia\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb border_radii=\u00bbon|50px|50px|50px|50px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.18.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.18.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.18.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb2em\u00bb header_line_height=\u00bb2em\u00bb header_4_line_height=\u00bb2em\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La diatermia puede combinarse bien y eficazmente con otras formas de terapia, en particular con la terapia de campo magn\u00e9tico.<\/p>\n<p>La particularidad del tratamiento con diatermia es que el paciente puede notar los efectos positivos tras unas pocas sesiones (1-2 tratamientos), mientras que la terapia de campo magn\u00e9tico suele requerir varias sesiones para lograr los efectos deseados. Los efectos de la terapia de campo magn\u00e9tico duran m\u00e1s, pero suelen ser m\u00e1s duraderos.<\/p>\n<h3>Como lo consigue?<\/h3>\n<p>Diatermia proporciona la transferencia de una energ\u00eda a una frecuencia determinada consiguiendo movilizar los iones intra y extracelulares provocando un aumento .<\/p>\n<h2><strong>Efectos Diatermia:<\/strong><\/h2>\n<p>Los efectos de la Tcare son un aumento en la actividad metab\u00f3lica con aumento de la producci\u00f3n de ATP, una aceleraci\u00f3n de la reparaci\u00f3n, u aumento en la circulaci\u00f3n a trav\u00e9s del calor, mejor oxigenaci\u00f3n de los tejidos y la reabsorci\u00f3n de edema.<\/p>\n<h3><\/h3>\n<h3>Indicaciones:<\/h3>\n<ul>\n<li>Lesiones musculo-esqueleticas como:\n<ul>\n<li>Contracturas<\/li>\n<li>Distensiones y roturas de fibras musculares<\/li>\n<li>Tendinopat\u00edas &#8211; trastornos de los tendones<\/li>\n<li>Esguinces<\/li>\n<li>Bursitis y sinovitis (inflamaci\u00f3n de bursas y articulaciones)<\/li>\n<\/ul>\n<\/li>\n<li>Procesos inflamatorios y degenerativos a nivel articular como:\n<ul>\n<li>Artrosis<\/li>\n<li>Discvitis (disco intervertebral)<\/li>\n<li>Artritis (inflamaci\u00f3n articular, reumatismo&#8230;)<\/li>\n<\/ul>\n<\/li>\n<li>Fisioterapia Deportiva:\n<ul>\n<li>Muy \u00fatil para la fatiga \/ sobrecarga en deportistas<\/li>\n<li>Prevenci\u00f3n y tratamiento de lesiones musculares<\/li>\n<li>Lesiones del cart\u00edlago<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Contraindicaciones:<\/h3>\n<ul>\n<li><strong>Absolutos:<\/strong>\n<ul>\n<li>Embarazo<\/li>\n<li>Marcapasos<\/li>\n<li>Implantes met\u00e1licos<\/li>\n<li>Implantes intrauterinos (DIU)<\/li>\n<li>Aumento del riesgo de hemorragia (Marcumar, anticoagulaci\u00f3n)<\/li>\n<li>Enfermedades inflamatorias agudas, fiebre y da\u00f1o vascular grave<\/li>\n<li>Tumores, met\u00e1stasis<\/li>\n<li>Reducci\u00f3n de la sensibilidad t\u00e9rmica y nociceptiva<\/li>\n<\/ul>\n<\/li>\n<li>Relativas:\n<ul>\n<li>Lesiones e infecciones de la piel<\/li>\n<li>Personas con insuficiencia cardiaca severa<\/li>\n<li>Mujeres durante el ciclo menstrual<\/li>\n<li>Diab\u00e9ticos con severos problemas vasculares<\/li>\n<\/ul>\n<\/li>\n<li>Precauciones:\n<ul>\n<li>Personas con riesgo de sufrir trombosis<\/li>\n<li>Personas que padecen de trastornos isqu\u00e9micos vasculares (tromboflebitis)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbServices\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#f1f5f7&#8243; custom_padding=\u00bb100px|0px|100px|0px|true|false\u00bb border_radii=\u00bb|15vw|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bboff|desktop\u00bb admin_label=\u00bbText Area\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb custom_padding_tablet=\u00bb100px||50px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.1&#8243; text_font=\u00bbMontserrat|300|||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb1.8em\u00bb ul_font=\u00bb||||||||\u00bb ol_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb|600|||||||\u00bb header_2_font_size=\u00bb34px\u00bb header_2_line_height=\u00bb1.5em\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb600px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb|||\u00bb custom_margin_tablet=\u00bb0px|50px||50px\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb|||\u00bb text_line_height_tablet=\u00bb1.8em\u00bb text_line_height_phone=\u00bb1.8em\u00bb text_line_height_last_edited=\u00bboff|desktop\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Nuestras terapias de un vistazo<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.19.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0025_eigenblut.png\u00bb title_text=\u00bbTOM_icons__0025_eigenblut\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbAutohemoterapia\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzY5In19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0028_stammzellen.png\u00bb title_text=\u00bbTOM_icons__0028_stammzellen\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbTerapia con c\u00e9lulas madre\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzcxIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0005_infiltration.png\u00bb title_text=\u00bbTOM_icons__0005_infiltration\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbTerapia de infiltraci\u00f3n\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzc1In19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.19.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0003_hyaluron.png\u00bb title_text=\u00bbTOM_icons__0003_hyaluron\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbTerapia de \u00e1cido hialur\u00f3nico\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzczIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2024\/05\/TOM_icons_Diathermie-300&#215;300.png\u00bb title_text=\u00bbTOM_icons_Diathermie\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbDiatermia\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1MTIyIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.25.1&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0026_monozyten.png\u00bb title_text=\u00bbTOM_icons__0026_monozyten\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbMonocitos\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzgxIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.19.0&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0001_lipocell.png\u00bb title_text=\u00bbTOM_icons__0001_lipocell\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbLipocell\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzgzIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0004_chrondofiller.png\u00bb title_text=\u00bbTOM_icons__0004_chrondofiller\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbChondrofiller\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzg1In19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb hover_enabled=\u00bb0&#8243; border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2024\/05\/TOM_icons_4TTherapie-300&#215;300.png\u00bb title_text=\u00bbTOM_icons_4TTherapie\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bb4T terapia\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1MTIzIn19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.25.1&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.25.1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0000_stosswellen-300&#215;300.png\u00bb title_text=\u00bbTOM_icons__0000_stosswellen\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbTerapia de ondas de choque\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzc3In19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.25.1&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.18.0&#8243; background_color=\u00bb#FFFFFF\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_icons__0007_bewegungsschiene.png\u00bb title_text=\u00bbTOM_icons__0007_bewegungsschiene\u00bb _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb30%\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_cta title=\u00bbAlquile una CPM\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQyMzg3In19@\u00bb button_text=\u00bbm\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.19.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb header_level=\u00bbh3&#8243; header_font=\u00bb||||||||\u00bb header_line_height=\u00bb1.5em\u00bb body_font=\u00bb||||||||\u00bb body_text_align=\u00bbcenter\u00bb body_text_color=\u00bb#404040&#8243; body_font_size=\u00bb15px\u00bb body_line_height=\u00bb1.5em\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#147b87&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_letter_spacing=\u00bb1px\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; background_layout=\u00bblight\u00bb custom_padding=\u00bb0px|30px|30px|30px|false|true\u00bb animation_direction=\u00bbtop\u00bb border_radii=\u00bb|||25px|25px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb30px\u00bb box_shadow_blur=\u00bb50px\u00bb box_shadow_spread=\u00bb-30px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#48d14c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#147b87&#8243; button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.25.1&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb|||\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diatermia Tecarterapia (transferencia de energ\u00eda capacitiva y resistiva)Se trata de una forma de terapia que utiliza corrientes el\u00e9ctricas y, por tanto, pertenece al grupo de las electroterapias. Aqu\u00ed se aplica corriente de una frecuencia determinada, que estimula el tejido biol\u00f3gico. Esto tiene un efecto antiinflamatorio y estimula y acelera los procesos naturales de curaci\u00f3n. Dependiendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":43172,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-45166","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diatermia - Traumatologie und Orthop\u00e4die Mallorca<\/title>\n<meta name=\"description\" content=\"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diatermia - Traumatologie und Orthop\u00e4die Mallorca\" \/>\n<meta property=\"og:description\" content=\"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/\" \/>\n<meta property=\"og:site_name\" content=\"Traumatologie und Orthop\u00e4die Mallorca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mallorca-Special-Surgery-103272311971779\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T13:17:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/diatermia\\\/\",\"url\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/diatermia\\\/\",\"name\":\"Diatermia - Traumatologie und Orthop\u00e4die Mallorca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#website\"},\"datePublished\":\"2024-05-16T13:09:01+00:00\",\"dateModified\":\"2025-09-09T13:17:24+00:00\",\"description\":\"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/diatermia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/diatermia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/diatermia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terapias y Tratamientos\",\"item\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/terapias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diatermia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/\",\"name\":\"Traumatologie und Orthop\u00e4die Mallorca\",\"description\":\"Dr. Patric Garcia\",\"publisher\":{\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#organization\",\"name\":\"Traumatologie und Orthop\u00e4die Mallorca\",\"url\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tom-mallorca.com\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/TOM_Logo_farbig-DE_RZ.png\",\"contentUrl\":\"https:\\\/\\\/tom-mallorca.com\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/TOM_Logo_farbig-DE_RZ.png\",\"width\":1113,\"height\":590,\"caption\":\"Traumatologie und Orthop\u00e4die Mallorca\"},\"image\":{\"@id\":\"https:\\\/\\\/tom-mallorca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mallorca-Special-Surgery-103272311971779\",\"https:\\\/\\\/www.instagram.com\\\/mallorcaspecialsurgery\\\/\",\"https:\\\/\\\/linkedin.com\\\/company\\\/mallorca-special-surgery\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diatermia - Traumatologie und Orthop\u00e4die Mallorca","description":"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/","og_locale":"es_ES","og_type":"article","og_title":"Diatermia - Traumatologie und Orthop\u00e4die Mallorca","og_description":"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.","og_url":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/","og_site_name":"Traumatologie und Orthop\u00e4die Mallorca","article_publisher":"https:\/\/www.facebook.com\/Mallorca-Special-Surgery-103272311971779","article_modified_time":"2025-09-09T13:17:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"26 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/","url":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/","name":"Diatermia - Traumatologie und Orthop\u00e4die Mallorca","isPartOf":{"@id":"https:\/\/tom-mallorca.com\/es\/#website"},"datePublished":"2024-05-16T13:09:01+00:00","dateModified":"2025-09-09T13:17:24+00:00","description":"En la terapia de ondas de choque, se utilizan ondas de presi\u00f3n especiales, que inducen la remodelaci\u00f3n y curaci\u00f3n de los tejidos a trav\u00e9s de la estimulaci\u00f3n.","breadcrumb":{"@id":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tom-mallorca.com\/es\/terapias\/diatermia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tom-mallorca.com\/es\/"},{"@type":"ListItem","position":2,"name":"Terapias y Tratamientos","item":"https:\/\/tom-mallorca.com\/es\/terapias\/"},{"@type":"ListItem","position":3,"name":"Diatermia"}]},{"@type":"WebSite","@id":"https:\/\/tom-mallorca.com\/es\/#website","url":"https:\/\/tom-mallorca.com\/es\/","name":"Traumatologie und Orthop\u00e4die Mallorca","description":"Dr. Patric Garcia","publisher":{"@id":"https:\/\/tom-mallorca.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tom-mallorca.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tom-mallorca.com\/es\/#organization","name":"Traumatologie und Orthop\u00e4die Mallorca","url":"https:\/\/tom-mallorca.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tom-mallorca.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_Logo_farbig-DE_RZ.png","contentUrl":"https:\/\/tom-mallorca.com\/new\/wp-content\/uploads\/2022\/10\/TOM_Logo_farbig-DE_RZ.png","width":1113,"height":590,"caption":"Traumatologie und Orthop\u00e4die Mallorca"},"image":{"@id":"https:\/\/tom-mallorca.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mallorca-Special-Surgery-103272311971779","https:\/\/www.instagram.com\/mallorcaspecialsurgery\/","https:\/\/linkedin.com\/company\/mallorca-special-surgery"]}]}},"_links":{"self":[{"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/45166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/comments?post=45166"}],"version-history":[{"count":8,"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/45166\/revisions"}],"predecessor-version":[{"id":46040,"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/45166\/revisions\/46040"}],"up":[{"embeddable":true,"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/pages\/43172"}],"wp:attachment":[{"href":"https:\/\/tom-mallorca.com\/es\/wp-json\/wp\/v2\/media?parent=45166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}